{"id":514,"date":"2022-11-03T16:14:59","date_gmt":"2022-11-03T15:14:59","guid":{"rendered":"https:\/\/coliving-sassenage.com\/?page_id=514"},"modified":"2023-12-26T17:19:31","modified_gmt":"2023-12-26T16:19:31","slug":"les-services","status":"publish","type":"page","link":"https:\/\/coliving-sassenage.com\/index.php\/les-services\/","title":{"rendered":"Les services"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-x-large-font-size\">Les services<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bien plus qu&rsquo;une semple location meubl\u00e9e, le coliving vous propose une formule cl\u00e9 en main pour faciliter grandement votre s\u00e9jour.<br>L&rsquo;ensemble des services suivants sont inclus dans le prix de votre location :<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td style=\"width:60px\"><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Eau, chauffage et \u00e9lectricit\u00e9<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Assurance habitation<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Wifi tr\u00e8s haut d\u00e9bit<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Electrom\u00e9nager haut de gamme<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Mobilier d\u00e9co<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Literie Tediber AIR3<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Linge de lit et serviettes<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Consommables (lessive, papier toilettes, cuisine, etc)<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Machine \u00e0 caf\u00e9 \u00e0 volont\u00e9<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>M\u00e9nage des communs<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Espace home-cin\u00e9ma<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Parking voiture privatif<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Borne de recharge pour v\u00e9hicule \u00e9lectrique<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Garage \u00e0 v\u00e9lo \u00e0 code<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Toutes taxes<\/td><\/tr><tr><td><img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"50\" class=\"wp-image-809\" style=\"width: 57px;\" src=\"http:\/\/coliving-sassenage.com\/wp-content\/uploads\/2023\/10\/case-50-1.png\" alt=\"\"><\/td><td>Une vie de r\u00e9sidence sympa et accueillante !<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les services Bien plus qu&rsquo;une semple location meubl\u00e9e, le coliving vous propose une formule cl\u00e9 en main pour faciliter grandement votre s\u00e9jour.L&rsquo;ensemble des services suivants sont inclus dans le prix de votre location : Eau, chauffage et \u00e9lectricit\u00e9 Assurance habitation Wifi tr\u00e8s haut d\u00e9bit Electrom\u00e9nager haut de gamme Mobilier d\u00e9co Literie Tediber AIR3 Linge de&hellip;&nbsp;<a href=\"https:\/\/coliving-sassenage.com\/index.php\/les-services\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Les services<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"class_list":["post-514","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/pages\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":13,"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/pages\/514\/revisions"}],"predecessor-version":[{"id":999,"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/pages\/514\/revisions\/999"}],"wp:attachment":[{"href":"https:\/\/coliving-sassenage.com\/index.php\/wp-json\/wp\/v2\/media?parent=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}